{"id":14,"date":"2013-12-30T07:34:34","date_gmt":"2013-12-30T07:34:34","guid":{"rendered":"http:\/\/themecanon.com\/themes\/kause\/?page_id=14"},"modified":"2016-08-20T20:59:12","modified_gmt":"2016-08-20T20:59:12","slug":"basilica-san-lorenzo-maggiore-milano","status":"publish","type":"page","link":"https:\/\/www.sanlorenzomaggiore.com\/","title":{"rendered":"Home"},"content":{"rendered":"<p>Basilica San Lorenzo Maggiore Milano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Basilica San Lorenzo Maggiore Milano<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"page-pagebuilder.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basilica San Lorenzo Maggiore Milano - Benvenuti<\/title>\n<meta name=\"description\" content=\"Basilica San Lorenzo Maggiore di Milano, la pi\u00f9 antica chiesa d&#039;Italia e di Milano. La sua comunit\u00e0 sorge accanto alla Cappella di Sant&#039;Aquilino.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sanlorenzomaggiore.com\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basilica San Lorenzo Maggiore Milano\" \/>\n<meta property=\"og:description\" content=\"Sito web della comunit\u00e0 della Basilica di San Lorenzo Maggiore alle colonne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sanlorenzomaggiore.com\/\" \/>\n<meta property=\"og:site_name\" content=\"Basilica San Lorenzo Maggiore\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-20T20:59:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\">\n\t<meta name=\"twitter:data1\" content=\"Mattia Colombo\">\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\">\n\t<meta name=\"twitter:data2\" content=\"0 minuti\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.sanlorenzomaggiore.com\/#website\",\"url\":\"http:\/\/www.sanlorenzomaggiore.com\/\",\"name\":\"Basilica San Lorenzo Maggiore\",\"description\":\"Educare \\u00e8 come seminare: il frutto non \\u00e8 garantito e non \\u00e8 immediato, ma se non si semina \\u00e8 certo che non ci sar\\u00e0 raccolto.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.sanlorenzomaggiore.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sanlorenzomaggiore.com\/#webpage\",\"url\":\"https:\/\/www.sanlorenzomaggiore.com\/\",\"name\":\"Basilica San Lorenzo Maggiore Milano - Benvenuti\",\"isPartOf\":{\"@id\":\"http:\/\/www.sanlorenzomaggiore.com\/#website\"},\"datePublished\":\"2013-12-30T07:34:34+00:00\",\"dateModified\":\"2016-08-20T20:59:12+00:00\",\"description\":\"Basilica San Lorenzo Maggiore di Milano, la pi\\u00f9 antica chiesa d'Italia e di Milano. La sua comunit\\u00e0 sorge accanto alla Cappella di Sant'Aquilino.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sanlorenzomaggiore.com\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/pages\/14"}],"collection":[{"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/comments?post=14"}],"version-history":[{"count":3,"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/pages\/14\/revisions\/2169"}],"wp:attachment":[{"href":"https:\/\/www.sanlorenzomaggiore.com\/index.php\/wp-json\/wp\/v2\/media?parent=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}